{"id":3437,"date":"2025-05-06T17:15:49","date_gmt":"2025-05-06T14:15:49","guid":{"rendered":"https:\/\/investconsultint.com\/invest-consult\/"},"modified":"2026-05-13T19:50:59","modified_gmt":"2026-05-13T16:50:59","slug":"invest-consult","status":"publish","type":"page","link":"https:\/\/investconsultint.com\/tr\/invest-consult\/","title":{"rendered":"Invest Consult"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"3437\" class=\"elementor elementor-3437 elementor-6\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6614b5a animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"6614b5a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-409610c elementor-widget elementor-widget-spacer\" data-id=\"409610c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-146671f elementor-headline--style-highlight elementor-widget elementor-widget-animated-headline\" data-id=\"146671f\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;marker&quot;:&quot;underline_zigzag&quot;,&quot;highlighted_text&quot;:&quot;Vergi cenneti&quot;,&quot;highlight_animation_duration&quot;:2000,&quot;headline_style&quot;:&quot;highlight&quot;,&quot;loop&quot;:&quot;yes&quot;,&quot;highlight_iteration_delay&quot;:8000}\" data-widget_type=\"animated-headline.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h2 class=\"elementor-headline\">\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">Vergi cennetine <br> ho\u015f geldiniz<\/span>\n\t\t\t\t<span class=\"elementor-headline-dynamic-wrapper elementor-headline-text-wrapper\">\n\t\t\t\t\t<span class=\"elementor-headline-dynamic-text elementor-headline-text-active\">Vergi cenneti<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"elementor-headline-plain-text elementor-headline-text-wrapper\">  Schengen'in.<\/span>\n\t\t\t\t\t<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dade69 elementor-widget elementor-widget-text-editor\" data-id=\"0dade69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"framer-styles-preset-pz5li8\" data-styles-preset=\"KRqmZpwbm\" data-pm-slice=\"1 1 []\">INVEST CONSULT INTERNATIONAL <br> Bulgaristan&#8217;da \u015firket kurulu\u015fu ve\ni\u015fletme y\u00f6netiminde g\u00fcvenilir orta\u011f\u0131n\u0131z<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bffa6e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"5bffa6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0130leti\u015fime ge\u00e7in<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ce64ee elementor-widget elementor-widget-spacer\" data-id=\"6ce64ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3dbd7d5 e-con-full e-flex e-con e-child\" data-id=\"3dbd7d5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-804c5b7 bdt-pagination-hide-yes bdt-carousel-style-carousel elementor-widget elementor-widget-prime-slider-tango\" data-id=\"804c5b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"prime-slider-tango.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bdt-prime-slider\">\n\t\t<div id=\"bdt-prime-slider-804c5b7\" class=\"bdt-prime-slider-tango elementor-swiper\" data-settings=\"{&quot;autoplay&quot;:{&quot;delay&quot;:2500},&quot;loop&quot;:true,&quot;speed&quot;:900,&quot;slidesPerView&quot;:1,&quot;slidesPerGroup&quot;:1,&quot;centeredSlides&quot;:true,&quot;effect&quot;:&quot;carousel&quot;,&quot;breakpoints&quot;:{&quot;689&quot;:{&quot;slidesPerView&quot;:2,&quot;spaceBetween&quot;:0,&quot;slidesPerGroup&quot;:1},&quot;999&quot;:{&quot;slidesPerView&quot;:3,&quot;spaceBetween&quot;:5,&quot;slidesPerGroup&quot;:1}},&quot;navigation&quot;:{&quot;nextEl&quot;:&quot;#bdt-prime-slider-804c5b7 .bdt-navigation-next&quot;,&quot;prevEl&quot;:&quot;#bdt-prime-slider-804c5b7 .bdt-navigation-prev&quot;},&quot;pagination&quot;:{&quot;el&quot;:&quot;#bdt-prime-slider-804c5b7 .swiper-pagination&quot;,&quot;clickable&quot;:&quot;true&quot;},&quot;coverflowEffect&quot;:{&quot;rotate&quot;:0,&quot;stretch&quot;:180,&quot;depth&quot;:100,&quot;modifier&quot;:1,&quot;slideShadows&quot;:true}}\">\n\t\t\t<div class=\"swiper-tango swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Tango Slider\" dir=\"ltr\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\n            <div class=\"swiper-slide bdt-item\">\n\t\t\t\t<div class=\"bdt-image-wrap\">\n\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"680\" height=\"730\" src=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/1.avif\" class=\"bdt-img\" alt=\"\" srcset=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/1.avif 680w, https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/1-279x300.avif 279w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"bdt-content-wrap\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n        \n            <div class=\"swiper-slide bdt-item\">\n\t\t\t\t<div class=\"bdt-image-wrap\">\n\t\t\t\t\t<img decoding=\"async\" width=\"680\" height=\"730\" src=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/3.avif\" class=\"bdt-img\" alt=\"\" srcset=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/3.avif 680w, https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/3-279x300.avif 279w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"bdt-content-wrap\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n        \n            <div class=\"swiper-slide bdt-item\">\n\t\t\t\t<div class=\"bdt-image-wrap\">\n\t\t\t\t\t<img decoding=\"async\" width=\"680\" height=\"730\" src=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/2.avif\" class=\"bdt-img\" alt=\"\" srcset=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/2.avif 680w, https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/05\/2-279x300.avif 279w\" sizes=\"(max-width: 680px) 100vw, 680px\" \/>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"bdt-content-wrap\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n        \t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t\t\t\n\t\t\t<div class=\"swiper-pagination reveal-muted\"><\/div>\n\t\t\t<!-- <div class=\"swiper-scrollbar\"><\/div> -->\n\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\n\t\t\t\t<\/div>\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3ec0d2 e-flex e-con-boxed e-con e-parent\" data-id=\"e3ec0d2\" data-element_type=\"container\" data-e-type=\"container\" id=\"kompetenzbereichen\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2226a0b elementor-widget elementor-widget-spacer\" data-id=\"2226a0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9b3f29 elementor-widget elementor-widget-heading\" data-id=\"e9b3f29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Her ad\u0131mda yan\u0131n\u0131zda\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56ec2e8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"56ec2e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-670c3e8 elementor-widget elementor-widget-text-editor\" data-id=\"670c3e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"framer-text framer-styles-preset-1dkk44e\" data-styles-preset=\"v4PWmgpAs\">Kurulu\u015ftan pazar liderli\u011fine kadar ICI, <br>m\u00fc\u015fterilerini ba\u015far\u0131ya giden yolda destekler<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0370302 elementor-widget elementor-widget-spacer\" data-id=\"0370302\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d294fe8 elementor-widget elementor-widget-text-editor\" data-id=\"d294fe8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"framer-1bu7oxl\" data-framer-name=\"Heading\"><div class=\"framer-18pcfok\" data-framer-component-type=\"RichTextContainer\"><p class=\"framer-text framer-styles-preset-1dkk44e\" data-styles-preset=\"v4PWmgpAs\">&#8230; ve hatta bunun \u00e7ok \u00f6tesinde<\/p><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2fdec71 e-con-full e-flex e-con e-child\" data-id=\"2fdec71\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0f56c85 e-grid e-con-full animated-slow elementor-invisible e-con e-child\" data-id=\"0f56c85\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e028cc2 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"e028cc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-default\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-diploma\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t\u015eirket kurulu\u015fu\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tSorunsuz ve son derece kolay! Bulgaristan'da \u015firketinizi kurarken ICI ile ya\u015fayaca\u011f\u0131n\u0131z deneyim b\u00f6yle olacak. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#frst\">\n\t\t\t\t\t\tDaha fazla bilgi\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5348fd8 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"5348fd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-default\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-document\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tMuhasebe\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tEvrak i\u015flerinden ve vergi dairesinden b\u0131kt\u0131n\u0131z m\u0131? Biz ilgileniyoruz! ICI yan\u0131n\u0131zdayken \u015firketinizin ba\u015far\u0131s\u0131na odaklanabilirsiniz.  \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#secnd\">\n\t\t\t\t\t\tDaha fazla bilgi\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8dc62d9 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"8dc62d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-default\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-user-check\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224 256c70.7 0 128-57.3 128-128S294.7 0 224 0 96 57.3 96 128s57.3 128 128 128zm89.6 32h-16.7c-22.2 10.2-46.9 16-72.9 16s-50.6-5.8-72.9-16h-16.7C60.2 288 0 348.2 0 422.4V464c0 26.5 21.5 48 48 48h352c26.5 0 48-21.5 48-48v-41.6c0-74.2-60.2-134.4-134.4-134.4zm323-128.4l-27.8-28.1c-4.6-4.7-12.1-4.7-16.8-.1l-104.8 104-45.5-45.8c-4.6-4.7-12.1-4.7-16.8-.1l-28.1 27.9c-4.7 4.6-4.7 12.1-.1 16.8l81.7 82.3c4.6 4.7 12.1 4.7 16.8.1l141.3-140.2c4.6-4.7 4.7-12.2.1-16.8z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\t\u0130nsan kaynaklar\u0131 y\u00f6netimi\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPersonel i\u015flerinizle ilgili her \u015fey \u2013 \u0130\u015fe al\u0131mdan i\u015f s\u00f6zle\u015fmelerine ve raporlamaya kadar her \u015feyi sizin i\u00e7in hallederiz.\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#thirdd\">\n\t\t\t\t\t\tDaha fazla bilgi\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf86798 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"cf86798\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-default\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-coins\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 405.3V448c0 35.3 86 64 192 64s192-28.7 192-64v-42.7C342.7 434.4 267.2 448 192 448S41.3 434.4 0 405.3zM320 128c106 0 192-28.7 192-64S426 0 320 0 128 28.7 128 64s86 64 192 64zM0 300.4V352c0 35.3 86 64 192 64s192-28.7 192-64v-51.6c-41.3 34-116.9 51.6-192 51.6S41.3 334.4 0 300.4zm416 11c57.3-11.1 96-31.7 96-55.4v-42.7c-23.2 16.4-57.3 27.6-96 34.5v63.6zM192 160C86 160 0 195.8 0 240s86 80 192 80 192-35.8 192-80-86-80-192-80zm219.3 56.3c60-10.8 100.7-32 100.7-56.3v-42.7c-35.5 25.1-96.5 38.6-160.7 41.8 29.5 14.3 51.2 33.5 60 57.2z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tVergi dan\u0131\u015fmanl\u0131\u011f\u0131\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tVergi konular\u0131 en ince ayr\u0131nt\u0131s\u0131na kadar netle\u015ftirilir. Bu, uzmanlar\u0131m\u0131z i\u00e7in en y\u00fcksek \u00f6nceliktir. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#fourthh\">\n\t\t\t\t\t\tDaha fazla bilgi\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8585b8e elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"8585b8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-default\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-checkmark\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tHukuki &amp; \u0130\u015f dan\u0131\u015fmanl\u0131\u011f\u0131\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tYenilikler getirmek veya yasal yap\u0131lar\u0131 de\u011fi\u015ftirmek mi? Biz bu konuda uzman\u0131z!  \n\u0130\u015fletme veya \u015fube a\u00e7\u0131l\u0131\u015flar\u0131 m\u0131? Endi\u015felenmeyin! Sizin i\u00e7in buraday\u0131z.  \n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#fifthh\">\n\t\t\t\t\t\tDaha fazla bilgi\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc64be4 elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"dc64be4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-content-item elementor-cta__content-item elementor-icon-wrapper elementor-cta__icon elementor-view-default\">\n\t\t\t\t\t\t<div class=\"elementor-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"icon icon-line-chart\"><\/i>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h2 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tAB fonlar\u0131\t\t\t\t\t<\/h2>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPotansiyelinizi AB deste\u011fiyle bir \u00fcst seviyeye ta\u015f\u0131y\u0131n. ICI, bu s\u00fcre\u00e7te sizi yetkinlik ve \u015feffafl\u0131kla destekler. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"#sixthh\">\n\t\t\t\t\t\tDaha fazla bilgi\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-aa6aa16 e-flex e-con-boxed e-con e-parent\" data-id=\"aa6aa16\" data-element_type=\"container\" data-e-type=\"container\" id=\"dienstleistungen\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d6edf8d elementor-widget elementor-widget-spacer\" data-id=\"d6edf8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8fe099b elementor-widget elementor-widget-heading\" data-id=\"8fe099b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hizmetler<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03ceae1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"03ceae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d434e1 e-con-full e-flex e-con e-child\" data-id=\"2d434e1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;laptop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t<div class=\"elementor-element elementor-element-d037153 e-grid e-con-full e-con e-child\" data-id=\"d037153\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-6589d08 e-con-full e-flex e-con e-child\" data-id=\"6589d08\" data-element_type=\"container\" data-e-type=\"container\" id=\"frst\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c395a8a elementor-widget elementor-widget-heading\" data-id=\"c395a8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bulgaristan'da<br>\u015firket kurulu\u015fu\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24f7ff0 elementor-widget elementor-widget-heading\" data-id=\"24f7ff0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">ICI, Bulgaristan'da \u015firket kurma s\u00fcrecinin tamam\u0131nda size destek olur. Do\u011fru yasal   \nyap\u0131n\u0131n se\u00e7iminden, kurulu\u015f sonras\u0131 tam kay\u0131t ve kurulum i\u015flemlerine kadar,   \n\u015firketinizin h\u0131zl\u0131, uygun ve sorunsuz bir \u015fekilde faaliyete ge\u00e7mesini sa\u011fl\u0131yoruz.  \nUzmanlar\u0131m\u0131z t\u00fcm idari ad\u0131mlar\u0131 koordine eder ve sizin ad\u0131n\u0131za yetkililerle ileti\u015fim  \nkurar.  <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e308fc0 elementor-widget elementor-widget-heading\" data-id=\"e308fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c4901d elementor-widget elementor-widget-text-editor\" data-id=\"2c4901d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u0130\u015f modelinize en uygun yasal yap\u0131 konusunda dan\u0131\u015fmanl\u0131k<\/li><li>\u015eirket ad\u0131n\u0131n rezervasyonu<\/li><li>Kurulu\u015f belgelerinin ve ana s\u00f6zle\u015fmenin haz\u0131rlanmas\u0131<\/li><li>Ortak ve y\u00f6netim yap\u0131lar\u0131n\u0131n olu\u015fturulmas\u0131nda destek<\/li><li>Tasdik i\u015flemlerinde koordinasyon ve temsil (gerekirse)<\/li><li>Bulgaristan Ticaret Sicili&#8217;ne kay\u0131t<\/li><li>BULSTAT ve istatistik makamlar\u0131na kay\u0131t<\/li><li>\u015eirket hesab\u0131 a\u00e7ma (destek ve belgeleme)<\/li><li>KDV kayd\u0131 (uygunsa)<\/li><li>Ulusal Vergi \u0130daresi&#8217;ne kay\u0131t<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c10d77e e-con-full e-flex e-con e-child\" data-id=\"c10d77e\" data-element_type=\"container\" data-e-type=\"container\" id=\"secnd\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8741b elementor-widget elementor-widget-heading\" data-id=\"7b8741b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Muhasebe ve Uyum  \n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14aa355 elementor-widget elementor-widget-heading\" data-id=\"14aa355\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">ICI, \u015firketinizin Bulgaristan mevzuat\u0131na tam olarak uygun \u015fekilde \u00e7al\u0131\u015fmas\u0131n\u0131  \nsa\u011flamak i\u00e7in kapsaml\u0131 muhasebe ve uyum hizmetleri sunmaktad\u0131r. Finansal   \nkay\u0131tlar\u0131n\u0131z\u0131, yasal raporlama y\u00fck\u00fcml\u00fcl\u00fcklerinizi ve vergi y\u00fck\u00fcml\u00fcl\u00fcklerinizi   \ny\u00f6netiyor ve \u015feffaf ileti\u015fim ve do\u011fru finansal denetim ile sizi g\u00fcncel tutuyoruz.  <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87a865d elementor-widget elementor-widget-heading\" data-id=\"87a865d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9388a60 elementor-widget elementor-widget-text-editor\" data-id=\"9388a60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li aria-level=\"1\">Bulgaristan GAAP ve vergi mevzuat\u0131na uygun muhasebe sistemlerinin kurulmas\u0131<\/li><li aria-level=\"1\">S\u00fcrekli muhasebe, i\u015flem kayd\u0131 ve d\u00f6nemsel mali tablolar<\/li><li aria-level=\"1\">KDV beyannamelerinin haz\u0131rlanmas\u0131 ve sunulmas\u0131 (VIES, Intrastat, uygulanabilirse)<\/li><li aria-level=\"1\">Sermaye kay\u0131tlar\u0131 ve amortisman planlar\u0131<\/li><li aria-level=\"1\">Maa\u015f bordrosu ve yasal bildirimlerin koordinasyonu (gerekirse)<\/li><li aria-level=\"1\">Y\u00f6netim raporlar\u0131 ve finansal analizlerin haz\u0131rlanmas\u0131<\/li><li aria-level=\"1\">Bilan\u00e7o, kar ve zarar tablosu ve ekleri dahil olmak \u00fczere y\u0131ll\u0131k mali tablolar<\/li><li aria-level=\"1\">Kurumlar vergisinin hesaplanmas\u0131 ve sunulmas\u0131<\/li><li aria-level=\"1\">Vergi daireleri nezdinde temsil, denetim ve kontroller s\u0131ras\u0131nda destek<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-009b75f e-con-full e-flex e-con e-child\" data-id=\"009b75f\" data-element_type=\"container\" data-e-type=\"container\" id=\"thirdd\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a148b5a elementor-widget elementor-widget-heading\" data-id=\"a148b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0130nsan kaynaklar\u0131 ve bordro\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8daf765 elementor-widget elementor-widget-heading\" data-id=\"8daf765\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">\u00c7al\u0131\u015fanlar\u0131n\u0131zla ilgili t\u00fcm konularda yan\u0131n\u0131zday\u0131z. Kapsaml\u0131 hizmetlerimiz, s\u00f6zle\u015fme olu\u015fturmadan bordro hesaplamaya ve sosyal g\u00fcvenlik ile vergi makamlar\u0131na bildirimlere kadar her \u015feyi i\u00e7erir. \u0130\u015f hukuku ve g\u00f6revlendirme konular\u0131nda da size kapsaml\u0131 dan\u0131\u015fmanl\u0131k sa\u011flar\u0131z.  \n\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc9681e elementor-widget elementor-widget-heading\" data-id=\"dc9681e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbb8795 elementor-widget elementor-widget-text-editor\" data-id=\"fbb8795\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li aria-level=\"1\">\u0130\u015f s\u00f6zle\u015fmelerinin olu\u015fturulmas\u0131 ve kayd\u0131<\/li><li aria-level=\"1\">Sosyal g\u00fcvenlik &amp; \u0130\u015f kurumuna kay\u0131t\/kay\u0131t iptali<\/li><li aria-level=\"1\">Vergi ve prim hesaplamas\u0131 dahil ayl\u0131k \u00fccret ve maa\u015f bordrosu <\/li><li aria-level=\"1\">Bordro kay\u0131tlar\u0131n\u0131n ve \u00f6deme listelerinin olu\u015fturulmas\u0131<\/li><li aria-level=\"1\">Vergi &amp; sosyal g\u00fcvenlik primlerinin \u00f6denmesi<\/li><li aria-level=\"1\">Makamlara bildirimler (NSSI, NRA vb.)<\/li><li aria-level=\"1\">\u00c7al\u0131\u015fma belgelerinin d\u00fczenlenmesi (\u00f6rn. bankalar i\u00e7in)<\/li><li aria-level=\"1\">G\u00f6revlendirmeler, ikramiyeler, izin, i\u015ften \u00e7\u0131karmalar konusunda destek<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f737005 e-con-full e-flex e-con e-child\" data-id=\"f737005\" data-element_type=\"container\" data-e-type=\"container\" id=\"fourthh\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-144b6a6 elementor-widget elementor-widget-heading\" data-id=\"144b6a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Finans ve Vergi Dan\u0131\u015fmanl\u0131\u011f\u0131  \n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10743fe elementor-widget elementor-widget-heading\" data-id=\"10743fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">ICI, \u015firket yap\u0131n\u0131z\u0131 optimize etmenize, yasal d\u00fczenlemelere uyum sa\u011flaman\u0131za ve   \nbilin\u00e7li kararlar alman\u0131za yard\u0131mc\u0131 olacak stratejik finans ve vergi dan\u0131\u015fmanl\u0131\u011f\u0131  \nhizmetleri sunmaktad\u0131r. Uzmanlar\u0131m\u0131z, i\u015f hedeflerinize uygun pratik dan\u0131\u015fmanl\u0131k  \nhizmetleri sunarak vergi risklerini en aza indirir ve genel finansal performans\u0131n\u0131z\u0131  \niyile\u015ftirir.  \n\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67aee6c elementor-widget elementor-widget-heading\" data-id=\"67aee6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f55de5 elementor-widget elementor-widget-text-editor\" data-id=\"5f55de5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u015eirket yap\u0131lar\u0131n\u0131n, vergi verimlili\u011finin ve genel finansal durumun analizi<\/li><li>Vergi planlamas\u0131 ve optimizasyon stratejileri<\/li><li>Kurumlar vergisi dahil olmak \u00fczere Bulgaristan ve uluslararas\u0131 vergi konular\u0131nda dan\u0131\u015fmanl\u0131k<\/li><li>KDV yap\u0131land\u0131rmas\u0131, s\u0131n\u0131r \u00f6tesi i\u015flemlerde dan\u0131\u015fmanl\u0131k ve \u00e7ifte vergilendirme anla\u015fmalar\u0131n\u0131n uygulanmas\u0131nda destek<\/li><li>Transfer fiyatlar\u0131 konusunda dan\u0131\u015fmanl\u0131k ve dok\u00fcmantasyon<\/li><li>Finansal tahminler, b\u00fct\u00e7eleme ve nakit ak\u0131\u015f\u0131 analizi<\/li><li>Yat\u0131r\u0131m yap\u0131land\u0131rmas\u0131 ve sermaye planlamas\u0131 konusunda dan\u0131\u015fmanl\u0131k<\/li><li>Sat\u0131n almalar ve yeniden yap\u0131land\u0131rmalar i\u00e7in due diligence deste\u011fi<\/li><li>Risk de\u011ferlendirmesi, uyum denetimleri ve vergi i\u015flemleri ve denetimlerinde temsil<\/li><li>S\u00fcrekli dan\u0131\u015fmanl\u0131k ve stratejik finansal destek<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe6a238 e-con-full e-flex e-con e-child\" data-id=\"fe6a238\" data-element_type=\"container\" data-e-type=\"container\" id=\"fifthh\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d70cfd8 elementor-widget elementor-widget-heading\" data-id=\"d70cfd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u0130\u015f ve Hukuk Dan\u0131\u015fmanl\u0131\u011f\u0131  \n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7816bf elementor-widget elementor-widget-heading\" data-id=\"d7816bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">ICI, yasal d\u00fczenlemelere uyumu sa\u011flamak, \u015firket \u00e7\u0131karlar\u0131n\u0131 korumak ve uzun   \nvadeli istikrar\u0131 g\u00fc\u00e7lendirmek amac\u0131yla entegre \u015firket ve hukuk dan\u0131\u015fmanl\u0131\u011f\u0131  \nhizmetleri sunarak \u015firketlere ve giri\u015fimcilere destek olur. Y\u00f6netim ekipleriyle yak\u0131n  \ni\u015fbirli\u011fi i\u00e7inde \u00e7al\u0131\u015farak, \u015firket hedeflerine ve de\u011fi\u015fen d\u00fczenleyici ortama uygun   \npratik hukuk \u00e7\u00f6z\u00fcmleri sunar\u0131z.  <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae3a455 elementor-widget elementor-widget-heading\" data-id=\"ae3a455\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5c9fd7 elementor-widget elementor-widget-text-editor\" data-id=\"c5c9fd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u015eirket yap\u0131s\u0131n\u0131n analizi ve yasal \u00e7er\u00e7eveye ili\u015fkin dan\u0131\u015fmanl\u0131k<\/li><li>\u015eirket kurulu\u015flar\u0131, yeniden yap\u0131land\u0131rmalar ve kurumsal y\u00f6neti\u015fim konusunda destek<\/li><li>Ticari s\u00f6zle\u015fmelerin ve anla\u015fmalar\u0131n tasla\u011f\u0131 ve incelenmesi<\/li><li>Yasal d\u00fczenlemelere uyum ve risk azaltma stratejilerinin de\u011ferlendirilmesi<\/li><li>\u015eirketin b\u00fcy\u00fcme hedeflerine uygun stratejik hukuk planlamas\u0131<\/li><li>\u015eirket politikalar\u0131n\u0131n ve i\u00e7 d\u00fczenleme \u00e7er\u00e7evelerinin geli\u015ftirilmesi<\/li><li>Hissedar ili\u015fkilerinde destek ve y\u00f6netim kuruluna dan\u0131\u015fmanl\u0131k<\/li><li>Birle\u015fme, sat\u0131n alma ve \u015firket i\u015flemlerinde hukuki destek<\/li><li>Anla\u015fmazl\u0131klar\u0131n \u00f6nlenmesi ve temsilin koordinasyonu i\u00e7in stratejiler<\/li><li>S\u00fcrekli hukuki dan\u0131\u015fmanl\u0131k ve stratejik \u015firket deste\u011fi<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d40f6b8 e-con-full e-flex e-con e-child\" data-id=\"d40f6b8\" data-element_type=\"container\" data-e-type=\"container\" id=\"sixthh\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-08c9861 elementor-widget elementor-widget-heading\" data-id=\"08c9861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">AB destek fonlar\u0131  \n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e9a43e6 elementor-widget elementor-widget-heading\" data-id=\"e9a43e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">ICI, inovasyon, geni\u015fleme ve uzun vadeli geli\u015fimi desteklemek i\u00e7in Avrupa   \nBirli\u011fi'nin destek programlar\u0131n\u0131n belirlenmesi, ba\u015fvurusu ve y\u00f6netimi konusunda   \n\u015firketlere destek olmaktad\u0131r. Ekibimiz, f\u0131rsatlar\u0131n de\u011ferlendirilmesi ve proje   \nyap\u0131land\u0131rmas\u0131ndan ba\u015fvuru haz\u0131rl\u0131\u011f\u0131 ve onay sonras\u0131 \u015fartlar\u0131n yerine getirilmesine   \nkadar t\u00fcm destek d\u00f6ng\u00fcs\u00fc boyunca size e\u015flik eder.  <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27ea578 elementor-widget elementor-widget-heading\" data-id=\"27ea578\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83f3149 elementor-widget elementor-widget-text-editor\" data-id=\"83f3149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Uygun AB destek programlar\u0131n\u0131n, hibelerin belirlenmesi ve uygunlu\u011fun de\u011ferlendirilmesi<\/li><li>Destek stratejisinin geli\u015ftirilmesi, proje konseptinin yap\u0131land\u0131r\u0131lmas\u0131 ve b\u00fct\u00e7eleme<\/li><li>Destek ba\u015fvurular\u0131n\u0131n, i\u015f planlar\u0131n\u0131n ve finansal tahminlerin haz\u0131rlanmas\u0131<\/li><li>\u0130dari makamlar ve arac\u0131larla koordinasyon<\/li><li>De\u011ferlendirme ve a\u00e7\u0131klama s\u00fcre\u00e7lerinde destek<\/li><li>Onay sonras\u0131 s\u00f6zle\u015fme m\u00fczakerelerinde destek<\/li><li>Proje uygulamas\u0131n\u0131n izlenmesi ve raporlama<\/li><li>Mali ve teknik raporlama, AB program gerekliliklerine uyum ve denetimlere haz\u0131rl\u0131k<\/li><li>Risk y\u00f6netimi ve d\u00fczeltici \u00f6nlemlerin planlanmas\u0131<\/li><li>Destek s\u00fcresi boyunca s\u00fcrekli dan\u0131\u015fmanl\u0131k<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f18e85 e-con-full e-flex e-con e-child\" data-id=\"6f18e85\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d81e155 elementor-widget elementor-widget-heading\" data-id=\"d81e155\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Vize ve Ta\u015f\u0131nma Hizmetleri  <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fcc717b elementor-widget elementor-widget-heading\" data-id=\"fcc717b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">ICI, vize ve g\u00f6\u00e7menlik konular\u0131nda kapsaml\u0131 destek sa\u011flayarak, Bulgaristan'a   \nta\u015f\u0131nan bireyler, giri\u015fimciler ve \u00e7al\u0131\u015fanlara yard\u0131mc\u0131 olmaktad\u0131r. Uygun oturma   \nizninin se\u00e7ilmesinden, sorunsuz bir \u015fekilde yerle\u015fmeye ve yerel d\u00fczenlemelere   \nuyum sa\u011flamaya kadar, s\u00fcrecin t\u00fcm a\u015famalar\u0131nda size e\u015flik ediyoruz. Ekibimiz, \nbelgelerin verimli bir \u015fekilde i\u015flenmesini ve yetkililerle yak\u0131n ileti\u015fim kurulmas\u0131n\u0131  \nsa\u011flar.  \n\n<\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e4bfba elementor-widget elementor-widget-heading\" data-id=\"4e4bfba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e7e5ab0 elementor-widget elementor-widget-text-editor\" data-id=\"e7e5ab0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Bireyler ve aileler i\u00e7in vize ve oturma izni se\u00e7eneklerinin ve g\u00f6\u00e7 stratejisinin de\u011ferlendirilmesi<\/li><li>Ba\u015fvuru belgelerinin haz\u0131rlanmas\u0131 ve kontrol\u00fc<\/li><li>Randevu al\u0131nmas\u0131 ve g\u00f6\u00e7menlik makamlar\u0131 nezdinde temsil edilmesi<\/li><li>Uzun vadeli, s\u00fcresiz oturma izni ve AB Mavi Kart ba\u015fvurular\u0131nda destek (uygunsa)<\/li><li>Aile birle\u015fimi prosed\u00fcrleri<\/li><li>\u0130kamet adresinin kayd\u0131, belediye formalitelerinin yerine getirilmesi ve ki\u015fisel kimlik numaras\u0131 ba\u015fvurusu<\/li><li>Oturma kart\u0131 ve sa\u011fl\u0131k sigortas\u0131 ba\u015fvurular\u0131nda destek<\/li><li>\u0130kametgah\u0131n vergiye ili\u015fkin etkileri konusunda dan\u0131\u015fmanl\u0131k<\/li><li>Y\u00f6neticiler ve \u00e7al\u0131\u015fanlar i\u00e7in ta\u015f\u0131nma deste\u011fi<\/li><li>Ta\u015f\u0131nma sonras\u0131 s\u00fcrekli destek ve dan\u0131\u015fmanl\u0131k<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-449b7a4 e-con-full e-flex e-con e-child\" data-id=\"449b7a4\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7129de elementor-widget elementor-widget-heading\" data-id=\"d7129de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ofis hizmetleri ve \u015firket merkezi<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e3c198 elementor-widget elementor-widget-heading\" data-id=\"5e3c198\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Bulgaristan'da bir i\u015f adresine mi ihtiyac\u0131n\u0131z var? ICI size posta y\u00f6nlendirme, resmi ileti\u015fim ve talep \u00fczerine telefon cevaplama veya yerinde toplant\u0131 odalar\u0131 gibi ek ofis hizmetleri dahil yasal olarak uyumlu bir \u015firket merkezi sunar. <\/h5>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-868b77f elementor-widget elementor-widget-heading\" data-id=\"868b77f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Ad\u0131mlar ve hizmetler:\n<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcb5b87 elementor-widget elementor-widget-text-editor\" data-id=\"dcb5b87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li aria-level=\"1\">Resmi bir i\u015f adresinin sa\u011flanmas\u0131 (yasal olarak uyumlu)<\/li><li aria-level=\"1\">Merkez sa\u011flama s\u00f6zle\u015fmesinin imzalanmas\u0131<\/li><li aria-level=\"1\">Posta al\u0131m\u0131 ve d\u00fczenli y\u00f6nlendirme (fiziksel veya dijital)<\/li><li aria-level=\"1\">Bu adresin Ticaret Sicili&#8217;ne kayd\u0131<\/li><li aria-level=\"1\">Makamlar ve i\u015f ortaklar\u0131 i\u00e7in tebligat adresi olarak kullan\u0131m<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81d5fc4 e-con-full e-flex e-con e-child\" data-id=\"81d5fc4\" data-element_type=\"container\" data-e-type=\"container\" id=\"mission\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c211b91 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c211b91\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:1000}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0130leti\u015fime ge\u00e7in<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a4179fe e-flex e-con-boxed e-con e-parent\" data-id=\"a4179fe\" data-element_type=\"container\" data-e-type=\"container\" id=\"preise\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a6495fb elementor-widget elementor-widget-spacer\" data-id=\"a6495fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0f97db elementor-widget elementor-widget-heading\" data-id=\"b0f97db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Fiyatland\u0131rma\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b94e8e7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"b94e8e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d3d908a e-con-full e-flex e-con e-child\" data-id=\"d3d908a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9011d0 elementor-widget elementor-widget-text-editor\" data-id=\"a9011d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Fiyatland\u0131rma hakk\u0131nda not<\/strong><br>Hizmetlerimiz gereksinimlerinize g\u00f6re \u00f6zelle\u015ftirildi\u011finden, fiyatland\u0131rma da bireysel olarak yap\u0131l\u0131r. <br>Belirtilen fiyatlar (varsa) yaln\u0131zca k\u0131lavuz niteli\u011findedir. <br>Somut bir teklif i\u00e7in l\u00fctfen bizimle ileti\u015fime ge\u00e7in \u2013 size memnuniyetle ba\u011flay\u0131c\u0131 olmayan ve \u00f6zel bir teklif haz\u0131rlar\u0131z.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6bf3c17 e-con-full animated-slow e-flex elementor-invisible e-con e-child\" data-id=\"6bf3c17\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d007b59 elementor-widget elementor-widget-html\" data-id=\"d007b59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<!-- PRICING TABLES \u2014 Elementor HTML widget (self-contained) -->\r\n<style>\r\n    \/* ===== Scope to this block ===== *\/\r\n    .eu-pricing-wrap {\r\n        --eu-green: #0f3e27;\r\n        --eu-green-2: #134f31;\r\n        --eu-green-light: #e6f2ec;\r\n        --eu-text: #0b1f16;\r\n        --eu-muted: #5a6b63;\r\n        --eu-border: #e8ecea;\r\n        --eu-shadow: 0 8px 28px rgba(0, 0, 0, .08), 0 2px 8px rgba(0, 0, 0, .06);\r\n        font-family: Inter, system-ui, -apple-system, Segoe UI, Roboto, Helvetica, Arial, sans-serif\r\n    }\r\n\r\n    .eu-pricing-wrap * {\r\n        box-sizing: border-box\r\n    }\r\n\r\n    .eu-pricing-grid {\r\n        display: grid;\r\n        gap: 20px\r\n    }\r\n\r\n    @media(min-width:768px) {\r\n        .eu-pricing-grid {\r\n            grid-template-columns: repeat(3, minmax(0, 1fr))\r\n        }\r\n    }\r\n\r\n    .eu-card {\r\n        background: #fff;\r\n        border-radius: 16px;\r\n        box-shadow: var(--eu-shadow);\r\n        overflow: hidden;\r\n        border: 1px solid #dfe8e3\r\n    }\r\n\r\n    .eu-card__head {\r\n        background: linear-gradient(0deg, var(--eu-green), var(--eu-green-2));\r\n        color: #fff;\r\n        padding: 18px 20px;\r\n        text-align: center\r\n    }\r\n\r\n    .eu-title {\r\n        font-weight: 700;\r\n        font-size: 20px;\r\n        letter-spacing: .2px\r\n    }\r\n\r\n    .eu-price {\r\n        display: flex;\r\n        align-items: flex-end;\r\n        justify-content: center;\r\n        gap: 8px;\r\n        margin-top: 8px\r\n    }\r\n\r\n    .eu-price .eu-old {\r\n        text-decoration: line-through;\r\n        opacity: .8;\r\n        font-weight: 600\r\n    }\r\n\r\n    .eu-price .eu-now {\r\n        font-size: 40px;\r\n        font-weight: 800;\r\n        line-height: 1\r\n    }\r\n\r\n    .eu-price .eu-currency {\r\n        font-size: 18px;\r\n        font-weight: 700;\r\n        margin-right: 2px;\r\n        opacity: .95\r\n    }\r\n\r\n    .eu-per {\r\n        font-size: 12px;\r\n        opacity: .9;\r\n        margin-top: 4px\r\n    }\r\n\r\n    .eu-onetime {\r\n        font-size: 12px;\r\n        color: #d1ebe0;\r\n        background: #0f3e271a;\r\n        border: 1px dashed #cfe3d8;\r\n        padding: 6px 10px;\r\n        border-radius: 10px;\r\n        display: inline-block;\r\n        margin-top: 10px\r\n    }\r\n\r\n    .eu-body {\r\n        padding: 14px 0\r\n    }\r\n\r\n    .eu-features {\r\n        margin: 0;\r\n        padding: 0;\r\n        list-style: none;\r\n        border-top: 1px solid var(--eu-border);\r\n        border-bottom: 1px solid var(--eu-border)\r\n    }\r\n\r\n    .eu-row {\r\n        display: flex;\r\n        align-items: flex-start;\r\n        gap: 10px;\r\n        padding: 12px 16px;\r\n        border-top: 1px solid var(--eu-border);\r\n        font-size: 14px;\r\n        color: var(--eu-text)\r\n    }\r\n\r\n    .eu-row:first-child {\r\n        border-top: 0\r\n    }\r\n\r\n    .eu-row svg {\r\n        min-width: 18px;\r\n        margin-top: 2px\r\n    }\r\n\r\n    .eu-ok {\r\n        color: #19a056\r\n    }\r\n\r\n    .eu-no {\r\n        color: #e0564c\r\n    }\r\n\r\n    .eu-muted {\r\n        color: var(--eu-muted)\r\n    }\r\n\r\n    .eu-actions {\r\n        padding: 16px\r\n    }\r\n\r\n    .eu-btn {\r\n        width: 100%;\r\n        display: inline-flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        gap: 8px;\r\n        background: var(--eu-green);\r\n        color: #fff;\r\n        border: 0;\r\n        border-radius: 14px;\r\n        padding: 12px 16px;\r\n        font-weight: 700;\r\n        cursor: pointer;\r\n        transition: transform .08s ease, box-shadow .2s ease\r\n    }\r\n\r\n    .eu-btn:hover {\r\n        transform: translateY(-1px);\r\n        box-shadow: 0 10px 24px rgba(15, 62, 39, .18)\r\n    }\r\n\r\n    .eu-btn:active {\r\n        transform: translateY(0)\r\n    }\r\n\r\n    \/* ===== Collapsible (shows 4 by default) ===== *\/\r\n    .eu-collapse {\r\n        overflow: hidden;\r\n        max-height: 0;\r\n        transition: max-height .35s ease\r\n    }\r\n\r\n    .eu-card[data-expanded=\"true\"] .eu-collapse {\r\n        max-height: 900px\r\n    }\r\n\r\n    \/* big enough for all *\/\r\n    .eu-toggle {\r\n        display: flex;\r\n        align-items: center;\r\n        justify-content: center;\r\n        gap: 8px;\r\n        padding: 12px 14px;\r\n        background: #f5faf7;\r\n        border-top: 1px solid var(--eu-border);\r\n        cursor: pointer;\r\n        color: var(--eu-green);\r\n        font-weight: 700\r\n    }\r\n\r\n    .eu-toggle svg {\r\n        transition: transform .25s ease\r\n    }\r\n\r\n    .eu-card[data-expanded=\"true\"] .eu-toggle svg {\r\n        transform: rotate(180deg)\r\n    }\r\n\r\n    .eu-toggle:hover {\r\n        background: #7d7d7d\r\n    }\r\n\r\n    \/* subtle highlight for the middle plan *\/\r\n    .eu-card.is-popular {\r\n        outline: 2px solid #a7dac0\r\n    }\r\n\r\n    .eu-badge {\r\n        position: absolute;\r\n        right: 14px;\r\n        top: 14px;\r\n        background: #dff3e8;\r\n        color: #0f3e27;\r\n        font-weight: 800;\r\n        font-size: 11px;\r\n        padding: 6px 8px;\r\n        border-radius: 999px;\r\n        border: 1px solid #bfe2ce\r\n    }\r\n\r\n    .eu-head-wrap {\r\n        position: relative\r\n    }\r\n\r\n\r\n    \/* Keep the brand green + header change from before *\/\r\n    .eu-pricing-wrap {\r\n        --eu-green: #003E13;\r\n        --eu-green-2: #003E13;\r\n    }\r\n\r\n    .eu-card__head {\r\n        background: #003E13 !important;\r\n        background-image: none !important;\r\n    }\r\n\r\n    \/* \"Sehe alle\" \u2014 link style (no bg), text + arrow #003E13 *\/\r\n    .eu-toggle {\r\n        background: transparent !important;\r\n        color: #003E13 !important;\r\n        \/* controls text AND arrow via currentColor *\/\r\n        border-top: 1px solid var(--eu-border);\r\n        box-shadow: none !important;\r\n    }\r\n\r\n    .eu-toggle:hover {\r\n        background: transparent !important;\r\n    }\r\n\r\n    .eu-toggle span {\r\n        color: #003E13 !important;\r\n    }\r\n\r\n    \/* Make sure the arrow is visible and green *\/\r\n    .eu-toggle svg {\r\n        display: inline-block !important;\r\n        \/* overrides any previous display:none *\/\r\n        color: #003E13 !important;\r\n        \/* currentColor for the SVG *\/\r\n    }\r\n\r\n    .eu-toggle svg path {\r\n        stroke: #003E13 !important;\r\n        \/* force the stroke color just in case *\/\r\n    }\r\n\r\n    \/* (Optional) keep the check\/cross colors consistent across themes *\/\r\n    .eu-ok,\r\n    .eu-ok * {\r\n        color: #19a056 !important;\r\n    }\r\n\r\n    .eu-ok path {\r\n        stroke: #19a056 !important;\r\n    }\r\n\r\n    .eu-no,\r\n    .eu-no * {\r\n        color: #e0564c !important;\r\n    }\r\n\r\n    .eu-no path {\r\n        stroke: #e0564c !important;\r\n    }\r\n<\/style>\r\n<div class=\"eu-pricing-wrap\">\r\n    <div class=\"eu-pricing-grid\"><!-- Ba\u015flang\u0131\u00e7 Paketi -->\r\n        <article class=\"eu-card\" data-expanded=\"false\">\r\n            <header class=\"eu-card__head\">\r\n                <div class=\"eu-title\">Ba\u015flang\u0131\u00e7 Paketi<\/div>\r\n                <div class=\"eu-price\"><span class=\"eu-currency\">\u20ac<\/span><span class=\"eu-now\">0<\/span><span\r\n                        class=\"eu-currency\">\u20ac<\/span><\/div>\r\n                <div class=\"eu-per\">\/ay<\/div>\r\n                <div class=\"eu-onetime\">Fiyat (tek seferlik) 849\u20ac<\/div>\r\n            <\/header>\r\n            <div class=\"eu-body\">\r\n                <ul class=\"eu-features\"><!-- Always visible (first 4) -->\r\n                    <li class=\"eu-row\"><!-- check --><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\"\r\n                            fill=\"none\" aria-hidden=\"true\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>EOOD\/OOD Kurulu\u015fu\r\n                    <\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>\u015eirket S\u00f6zle\u015fmesi ve Noter Hizmeti\r\n                    <\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>Sermaye i\u00e7in Banka Hesab\u0131\r\n                    <\/li>\r\n                    <li class=\"eu-row\"><!-- cross --><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\"\r\n                            fill=\"none\">\r\n                            <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                stroke-linecap=\"round\" \/>\r\n                        <\/svg>Online Bankac\u0131l\u0131k Dahil Ticari Hesap\r\n                    <\/li><!-- Collapsible rest -->\r\n                    <div class=\"eu-collapse\">\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>KDV Numaras\u0131 Ba\u015fvurusu\r\n                        <\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>T\u00fcm Kurulu\u015f Belgelerinin \u00c7evirisi\r\n                        <\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Posta Y\u00f6nlendirme Dahil \u015eirket Merkezi\r\n                        <\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>A\u00e7\u0131l\u0131\u015f Bilan\u00e7osu\r\n                        <\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Muhasebe (\u0130htiyaca G\u00f6re De\u011fi\u015ftirilebilir)\r\n                        <\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Vergi Kayd\u0131 (NRA)\r\n                        <\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Y\u0131ll\u0131k Bilan\u00e7o\r\n                        <\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\" fill=\"none\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Ofis Hizmeti\r\n                        <\/li>\r\n                    <\/div><button class=\"eu-toggle\" type=\"button\"><span>T\u00fcm\u00fcn\u00fc G\u00f6r<\/span><svg width=\"16\" height=\"16\"\r\n                            viewBox=\"0 0 24 24\" fill=\"none\" aria-hidden=\"true\">\r\n                            <path d=\"M6 9l6 6 6-6\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg><\/button>\r\n                <\/ul>\r\n                <div class=\"eu-actions\"><button class=\"eu-btn\" type=\"button\">\u015eirket Kur<\/button><\/div>\r\n            <\/div>\r\n        <\/article><!-- Temel Paket -->\r\n        <article class=\"eu-card is-popular\" data-expanded=\"false\">\r\n            <div class=\"eu-head-wrap\"><span class=\"eu-badge\">Pop\u00fcler<\/span>\r\n                <header class=\"eu-card__head\">\r\n                    <div class=\"eu-title\">Temel Paket<\/div>\r\n                    <div class=\"eu-price\"><span class=\"eu-old\">\u20ac89<\/span><span class=\"eu-currency\">\u20ac<\/span><span\r\n                            class=\"eu-now\">49<\/span><span class=\"eu-currency\">\u20ac<\/span><\/div>\r\n                    <div class=\"eu-per\">\/ay<\/div>\r\n                    <div class=\"eu-onetime\">Fiyat (tek seferlik) 1149\u20ac<\/div>\r\n                <\/header>\r\n            <\/div>\r\n            <div class=\"eu-body\">\r\n                <ul class=\"eu-features\"><!-- Always visible -->\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>EOOD\/OOD Kurulu\u015fu<\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>\u015eirket S\u00f6zle\u015fmesi ve Noter Hizmeti<\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>Sermaye i\u00e7in Banka Hesab\u0131<\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>Online Bankac\u0131l\u0131k Dahil Ticari Hesap<\/li><!-- Collapsible -->\r\n                    <div class=\"eu-collapse\">\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>KDV Numaras\u0131 Ba\u015fvurusu<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>T\u00fcm Kurulu\u015f Belgelerinin \u00c7evirisi<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>Posta Y\u00f6nlendirme Dahil \u015eirket Merkezi<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>A\u00e7\u0131l\u0131\u015f Bilan\u00e7osu<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Muhasebe (\u0130htiyaca G\u00f6re De\u011fi\u015ftirilebilir)<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Vergi Kayd\u0131 (NRA)<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Y\u0131ll\u0131k Bilan\u00e7o<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-no\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M18 6L6 18M6 6l12 12\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" \/>\r\n                            <\/svg>Ofis Hizmeti<\/li>\r\n                    <\/div><button class=\"eu-toggle\" type=\"button\"><span>T\u00fcm\u00fcn\u00fc G\u00f6r<\/span><svg width=\"16\" height=\"16\"\r\n                            viewBox=\"0 0 24 24\" fill=\"none\">\r\n                            <path d=\"M6 9l6 6 6-6\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg><\/button>\r\n                <\/ul>\r\n                <div class=\"eu-actions\"><button class=\"eu-btn\" type=\"button\">\u015eirket Kur<\/button><\/div>\r\n            <\/div>\r\n        <\/article><!-- Business Paket -->\r\n        <article class=\"eu-card\" data-expanded=\"false\">\r\n            <header class=\"eu-card__head\">\r\n                <div class=\"eu-title\">Business Paket<\/div>\r\n                <div class=\"eu-price\"><span class=\"eu-old\">\u20ac339<\/span><span class=\"eu-currency\">\u20ac<\/span><span\r\n                        class=\"eu-now\">289<\/span><span class=\"eu-currency\">\u20ac<\/span><\/div>\r\n                <div class=\"eu-per\">\/ay<\/div>\r\n                <div class=\"eu-onetime\">Fiyat (tek seferlik) 1249\u20ac<\/div>\r\n            <\/header>\r\n            <div class=\"eu-body\">\r\n                <ul class=\"eu-features\"><!-- Always visible -->\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>EOOD\/OOD Kurulu\u015fu<\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>\u015eirket S\u00f6zle\u015fmesi ve Noter Hizmeti<\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>Sermaye i\u00e7in Banka Hesab\u0131<\/li>\r\n                    <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                            <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg>Online Bankac\u0131l\u0131k Dahil Ticari Hesap<\/li><!-- Collapsible -->\r\n                    <div class=\"eu-collapse\">\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>KDV Numaras\u0131 Ba\u015fvurusu<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>T\u00fcm Kurulu\u015f Belgelerinin \u00c7evirisi<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>Posta Y\u00f6nlendirme Dahil \u015eirket Merkezi<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>A\u00e7\u0131l\u0131\u015f Bilan\u00e7osu<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>Muhasebe (\u0130htiyaca G\u00f6re De\u011fi\u015ftirilebilir)<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>Vergi Kayd\u0131 (NRA)<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>Y\u0131ll\u0131k Bilan\u00e7o<\/li>\r\n                        <li class=\"eu-row\"><svg class=\"eu-ok\" width=\"18\" height=\"18\" viewBox=\"0 0 24 24\">\r\n                                <path d=\"M20 6L9 17l-5-5\" stroke=\"currentColor\" stroke-width=\"2.4\"\r\n                                    stroke-linecap=\"round\" stroke-linejoin=\"round\" \/>\r\n                            <\/svg>Ofis Hizmeti<\/li>\r\n                    <\/div><button class=\"eu-toggle\" type=\"button\"><span>T\u00fcm\u00fcn\u00fc G\u00f6r<\/span><svg width=\"16\" height=\"16\"\r\n                            viewBox=\"0 0 24 24\" fill=\"none\">\r\n                            <path d=\"M6 9l6 6 6-6\" stroke=\"currentColor\" stroke-width=\"2.4\" stroke-linecap=\"round\"\r\n                                stroke-linejoin=\"round\" \/>\r\n                        <\/svg><\/button>\r\n                <\/ul>\r\n                <div class=\"eu-actions\"><button class=\"eu-btn\" type=\"button\">\u015eirket Kur<\/button><\/div>\r\n            <\/div>\r\n        <\/article>\r\n    <\/div>\r\n<\/div>\r\n<script>\/* Smooth open\/close for each card *\/\r\n    (function () {\r\n        const cards = document.querySelectorAll('.eu-card');\r\n        cards.forEach(card => {\r\n            const toggle = card.querySelector('.eu-toggle');\r\n            const collapse = card.querySelector('.eu-collapse');\r\n            if (!toggle || !collapse) return;\r\n\r\n            \/\/ ensure proper height on open\r\n            const setHeight = (open) => {\r\n                if (open) {\r\n                    collapse.style.maxHeight = collapse.scrollHeight + 'px';\r\n                } else {\r\n                    collapse.style.maxHeight = 0;\r\n                }\r\n            };\r\n\r\n            \/\/ init closed\r\n            setHeight(false);\r\n\r\n            toggle.addEventListener('click', () => {\r\n                const isOpen = card.getAttribute('data-expanded') === 'true';\r\n                card.setAttribute('data-expanded', String(!isOpen));\r\n                setHeight(!isOpen);\r\n                \/\/ label swap\r\n                const span = toggle.querySelector('span');\r\n                if (span) { span.textContent = isOpen ? 'T\u00fcm\u00fcn\u00fc G\u00f6r' : 'Daha Az G\u00f6ster'; }\r\n            });\r\n\r\n            \/\/ Recompute on resize to keep animation smooth\r\n            window.addEventListener('resize', () => {\r\n                if (card.getAttribute('data-expanded') === 'true') {\r\n                    collapse.style.maxHeight = collapse.scrollHeight + 'px';\r\n                }\r\n            });\r\n        });\r\n    })();\r\n\r\n    \/* HARD-FORCE icon colors so theme\/Elementor can't override *\/\r\n    (function () {\r\n        function forceIconColors() {\r\n            \/\/ Green checks\r\n            document.querySelectorAll('.eu-features .eu-row svg.eu-ok').forEach(svg => {\r\n                svg.style.setProperty('color', '#19a056', 'important');\r\n                svg.style.setProperty('filter', 'none', 'important');\r\n                svg.style.setProperty('opacity', '1', 'important');\r\n                svg.style.setProperty('transform', 'none', 'important');\r\n                svg.querySelectorAll('path').forEach(p => {\r\n                    p.setAttribute('fill', 'none');\r\n                    p.style.setProperty('stroke', '#19a056', 'important');\r\n                    p.style.setProperty('strokeWidth', '2.4', 'important');\r\n                });\r\n            });\r\n\r\n            \/\/ Red crosses\r\n            document.querySelectorAll('.eu-features .eu-row svg.eu-no').forEach(svg => {\r\n                svg.style.setProperty('color', '#e0564c', 'important');\r\n                svg.style.setProperty('filter', 'none', 'important');\r\n                svg.style.setProperty('opacity', '1', 'important');\r\n                svg.style.setProperty('transform', 'none', 'important');\r\n                svg.querySelectorAll('path').forEach(p => {\r\n                    p.setAttribute('fill', 'none');\r\n                    p.style.setProperty('stroke', '#e0564c', 'important');\r\n                    p.style.setProperty('strokeWidth', '2.4', 'important');\r\n                });\r\n            });\r\n        }\r\n\r\n        \/\/ Run once DOM is ready\r\n        if (document.readyState === 'loading') {\r\n            document.addEventListener('DOMContentLoaded', forceIconColors);\r\n        } else {\r\n            forceIconColors();\r\n        }\r\n\r\n        \/\/ If Elementor re-renders widgets dynamically, run again after a short delay\r\n        setTimeout(forceIconColors, 300);\r\n    })();\r\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b85302e e-flex e-con-boxed e-con e-parent\" data-id=\"b85302e\" data-element_type=\"container\" data-e-type=\"container\" id=\"faq\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a14fab4 elementor-widget elementor-widget-spacer\" data-id=\"a14fab4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6263cc2 elementor-widget elementor-widget-heading\" data-id=\"6263cc2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">S\u0131k\u00e7a Sorulan Sorular<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eb5131 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3eb5131\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3913fe5 elementor-widget elementor-widget-text-editor\" data-id=\"3913fe5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"framer-styles-preset-pz5li8\" data-styles-preset=\"KRqmZpwbm\" data-pm-slice=\"1 1 []\">En s\u0131k sorulan sorulara h\u0131zl\u0131 yan\u0131tlar al\u0131n<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33e2cb3 elementor-widget elementor-widget-n-accordion\" data-id=\"33e2cb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-5440\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-5440\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> I. Bulgaristan'da \u015firket kurulu\u015fu <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-5440\" class=\"elementor-element elementor-element-3a51f33 e-con-full e-flex e-con e-child\" data-id=\"3a51f33\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c3b3ee0 elementor-widget elementor-widget-n-accordion\" data-id=\"c3b3ee0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:250,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2050\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2050\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Bulgaristan'da hangi \u015firket t\u00fcrleri var? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-5440 e-n-accordion-item-2050\" class=\"elementor-element elementor-element-b0a8c8b e-con-full e-flex e-con e-child\" data-id=\"b0a8c8b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-5440 e-n-accordion-item-2050\" class=\"elementor-element elementor-element-e78f3b2 e-flex e-con-boxed e-con e-child\" data-id=\"e78f3b2\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55af060 elementor-widget elementor-widget-heading\" data-id=\"55af060\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"><h4>Bulgaristan'da en yayg\u0131n yasal yap\u0131lar \u015funlard\u0131r:<\/h4>\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec6034b elementor-widget elementor-widget-text-editor\" data-id=\"ec6034b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>EOOD<\/strong> (Tek ki\u015filik limited \u015firket)<\/li><li><strong>OOD<\/strong> (\u00c7ok ortakl\u0131 limited \u015firket)<\/li><li><strong>ET<\/strong> (\u015eah\u0131s i\u015fletmesi)<\/li><li><strong>AD<\/strong> (Anonim \u015firket)<br>EOOD, \u00f6zellikle yabanc\u0131 giri\u015fimciler aras\u0131nda pop\u00fclerdir.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2051\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2051\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Bulgaristan'da \u015firket kurulu\u015fu ne kadar s\u00fcrer? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-5440 e-n-accordion-item-2051\" class=\"elementor-element elementor-element-37aeff1 e-con-full e-flex e-con e-child\" data-id=\"37aeff1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-5440 e-n-accordion-item-2051\" class=\"elementor-element elementor-element-a612eaf e-flex e-con-boxed e-con e-child\" data-id=\"a612eaf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-480159b elementor-widget elementor-widget-heading\" data-id=\"480159b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">T\u00fcm belgeler eksiksiz ve do\u011fru oldu\u011fu takdirde kurulu\u015f genellikle 5-7 i\u015f g\u00fcn\u00fc s\u00fcrer.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2052\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2052\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Bulgaristan hangi vergi avantajlar\u0131n\u0131 sunuyor? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-5440 e-n-accordion-item-2052\" class=\"elementor-element elementor-element-58b0503 e-flex e-con-boxed e-con e-child\" data-id=\"58b0503\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-5440 e-n-accordion-item-2052\" class=\"elementor-element elementor-element-b96404e e-con-full e-flex e-con e-child\" data-id=\"b96404e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0897add elementor-widget elementor-widget-text-editor\" data-id=\"0897add\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Kurumlar vergisi: <strong>%10<\/strong> (AB&#8217;deki en d\u00fc\u015f\u00fcklerden biri)<\/li><li>Gelir vergisi: <strong>%10<\/strong> sabit<\/li><li>Temett\u00fc vergisi: <strong>%5<\/strong><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Bulgaristan'da hangi \\u015firket t\\u00fcrleri var?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Bulgaristan'da en yayg\\u0131n yasal yap\\u0131lar \\u015funlard\\u0131r:\\n\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\tEOOD (Tek ki\\u015filik limited \\u015firket)OOD (\\u00c7ok ortakl\\u0131 limited \\u015firket)ET (\\u015eah\\u0131s i\\u015fletmesi)AD (Anonim \\u015firket)EOOD, \\u00f6zellikle yabanc\\u0131 giri\\u015fimciler aras\\u0131nda pop\\u00fclerdir.\"}},{\"@type\":\"Question\",\"name\":\"Bulgaristan'da \\u015firket kurulu\\u015fu ne kadar s\\u00fcrer?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"T\\u00fcm belgeler eksiksiz ve do\\u011fru oldu\\u011fu takdirde kurulu\\u015f genellikle 5-7 i\\u015f g\\u00fcn\\u00fc s\\u00fcrer.\"}},{\"@type\":\"Question\",\"name\":\"Bulgaristan hangi vergi avantajlar\\u0131n\\u0131 sunuyor?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Kurumlar vergisi: %10 (AB&#8217;deki en d\\u00fc\\u015f\\u00fcklerden biri)Gelir vergisi: %10 sabitTemett\\u00fc vergisi: %5\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2eff07c elementor-widget elementor-widget-n-accordion\" data-id=\"2eff07c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-4920\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-4920\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> II. Muhasebe ve vergi y\u00fck\u00fcml\u00fcl\u00fckleri <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-4920\" class=\"elementor-element elementor-element-1489b0e e-con-full e-flex e-con e-child\" data-id=\"1489b0e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9efdba8 elementor-widget elementor-widget-n-accordion\" data-id=\"9efdba8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:250,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1660\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1660\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Bulgaristan'da her \u015firket muhasebe tutmak zorunda m\u0131? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-4920 e-n-accordion-item-1660\" class=\"elementor-element elementor-element-5eb70c6 e-flex e-con-boxed e-con e-child\" data-id=\"5eb70c6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-4920 e-n-accordion-item-1660\" class=\"elementor-element elementor-element-adc228d e-con-full e-flex e-con e-child\" data-id=\"adc228d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c995d27 elementor-widget elementor-widget-text-editor\" data-id=\"c995d27\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Evet, her t\u00fczel ki\u015fi, faaliyetinden veya ciro tutar\u0131ndan ba\u011f\u0131ms\u0131z olarak yasal olarak d\u00fczenli muhasebe tutmakla y\u00fck\u00fcml\u00fcd\u00fcr. ICI bununla b\u00fcy\u00fck bir \u00f6zenle ilgilenir. <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1661\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1661\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Genel m\u00fcd\u00fcr olarak y\u00fck\u00fcml\u00fcl\u00fcklerim nelerdir? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-4920 e-n-accordion-item-1661\" class=\"elementor-element elementor-element-4a219ca e-flex e-con-boxed e-con e-child\" data-id=\"4a219ca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-4920 e-n-accordion-item-1661\" class=\"elementor-element elementor-element-d285094 e-con-full e-flex e-con e-child\" data-id=\"d285094\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8a643c2 elementor-widget elementor-widget-text-editor\" data-id=\"8a643c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Defterlerin d\u00fczenli tutulmas\u0131<\/li><li>T\u00fcm beyannamelerin zaman\u0131nda verilmesi<\/li><li>\u0130\u015f belgelerinin saklanma y\u00fck\u00fcml\u00fcl\u00fc\u011f\u00fc (10 y\u0131l)<\/li><li>T\u00fcm vergi ve sosyal g\u00fcvenlik \u00f6demelerinden sorumluluk<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Bulgaristan'da her \\u015firket muhasebe tutmak zorunda m\\u0131?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Evet, her t\\u00fczel ki\\u015fi, faaliyetinden veya ciro tutar\\u0131ndan ba\\u011f\\u0131ms\\u0131z olarak yasal olarak d\\u00fczenli muhasebe tutmakla y\\u00fck\\u00fcml\\u00fcd\\u00fcr. ICI bununla b\\u00fcy\\u00fck bir \\u00f6zenle ilgilenir.\"}},{\"@type\":\"Question\",\"name\":\"Genel m\\u00fcd\\u00fcr olarak y\\u00fck\\u00fcml\\u00fcl\\u00fcklerim nelerdir?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Defterlerin d\\u00fczenli tutulmas\\u0131T\\u00fcm beyannamelerin zaman\\u0131nda verilmesi\\u0130\\u015f belgelerinin saklanma y\\u00fck\\u00fcml\\u00fcl\\u00fc\\u011f\\u00fc (10 y\\u0131l)T\\u00fcm vergi ve sosyal g\\u00fcvenlik \\u00f6demelerinden sorumluluk\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0d380d elementor-widget elementor-widget-n-accordion\" data-id=\"d0d380d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2180\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2180\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> III. Vergi dan\u0131\u015fmanl\u0131\u011f\u0131 &amp; Optimizasyon <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2180\" class=\"elementor-element elementor-element-f04e062 e-con-full e-flex e-con e-child\" data-id=\"f04e062\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-20a5e12 elementor-widget elementor-widget-n-accordion\" data-id=\"20a5e12\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:250,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3420\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3420\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Bulgaristan \u015firketimi di\u011fer \u00fclkelerdeki i\u015fler i\u00e7in kullanabilir miyim? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-2180 e-n-accordion-item-3420\" class=\"elementor-element elementor-element-9e3292a e-flex e-con-boxed e-con e-child\" data-id=\"9e3292a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-2180 e-n-accordion-item-3420\" class=\"elementor-element elementor-element-ea623c7 e-con-full e-flex e-con e-child\" data-id=\"ea623c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7421f20 elementor-widget elementor-widget-text-editor\" data-id=\"7421f20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Evet, Bulgaristan&#8217;da kay\u0131tl\u0131 bir \u015firket, hedef \u00fclkedeki yerel d\u00fczenlemelere uydu\u011fu s\u00fcrece <strong>uluslararas\u0131 faaliyet<\/strong> g\u00f6sterebilir. \u00d6zellikle \u00e7evrimi\u00e7i hizmetlerde bu yayg\u0131nd\u0131r. <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3421\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3421\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Vergi planlamas\u0131nda en yayg\u0131n hatalar nelerdir? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-2180 e-n-accordion-item-3421\" class=\"elementor-element elementor-element-bcc94e4 e-flex e-con-boxed e-con e-child\" data-id=\"bcc94e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-2180 e-n-accordion-item-3421\" class=\"elementor-element elementor-element-161e9fb e-con-full e-flex e-con e-child\" data-id=\"161e9fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f38ba6 elementor-widget elementor-widget-text-editor\" data-id=\"9f38ba6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>\u00d6zel ve i\u015f giderleri aras\u0131nda do\u011fru ayr\u0131m yap\u0131lmamas\u0131<\/li><li>Ge\u00e7 verilen veya verilmeyen beyannameler<\/li><li>Kay\u0131t d\u0131\u015f\u0131 \u00e7al\u0131\u015fanlar veya genel m\u00fcd\u00fcrler<\/li><li>Yurtd\u0131\u015f\u0131 ili\u015fkilerde bildirim y\u00fck\u00fcml\u00fcl\u00fckleri konusunda bilgi eksikli\u011fi<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Bulgaristan \\u015firketimi di\\u011fer \\u00fclkelerdeki i\\u015fler i\\u00e7in kullanabilir miyim?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Evet, Bulgaristan&#8217;da kay\\u0131tl\\u0131 bir \\u015firket, hedef \\u00fclkedeki yerel d\\u00fczenlemelere uydu\\u011fu s\\u00fcrece uluslararas\\u0131 faaliyet g\\u00f6sterebilir. \\u00d6zellikle \\u00e7evrimi\\u00e7i hizmetlerde bu yayg\\u0131nd\\u0131r.\"}},{\"@type\":\"Question\",\"name\":\"Vergi planlamas\\u0131nda en yayg\\u0131n hatalar nelerdir?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"\\u00d6zel ve i\\u015f giderleri aras\\u0131nda do\\u011fru ayr\\u0131m yap\\u0131lmamas\\u0131Ge\\u00e7 verilen veya verilmeyen beyannamelerKay\\u0131t d\\u0131\\u015f\\u0131 \\u00e7al\\u0131\\u015fanlar veya genel m\\u00fcd\\u00fcrlerYurtd\\u0131\\u015f\\u0131 ili\\u015fkilerde bildirim y\\u00fck\\u00fcml\\u00fcl\\u00fckleri konusunda bilgi eksikli\\u011fi\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-753ca9b elementor-widget elementor-widget-n-accordion\" data-id=\"753ca9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1220\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1220\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> IV. Di\u011fer sorular <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1220\" class=\"elementor-element elementor-element-d69e04f e-con-full e-flex e-con e-child\" data-id=\"d69e04f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5bce40e elementor-widget elementor-widget-n-accordion\" data-id=\"5bce40e\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:250,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9620\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9620\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Banka hesab\u0131 a\u00e7\u0131l\u0131\u015f\u0131 veya oturma izni konusunda destek sa\u011fl\u0131yor musunuz? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-1220 e-n-accordion-item-9620\" class=\"elementor-element elementor-element-77392ae e-flex e-con-boxed e-con e-child\" data-id=\"77392ae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-1220 e-n-accordion-item-9620\" class=\"elementor-element elementor-element-9b46f56 e-con-full e-flex e-con e-child\" data-id=\"9b46f56\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f13a723 elementor-widget elementor-widget-text-editor\" data-id=\"f13a723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Evet, <strong>hesap a\u00e7\u0131l\u0131\u015f\u0131nda<\/strong>, <strong>UID numaras\u0131<\/strong> ba\u015fvurusunda, <strong>oturma kart\u0131 al\u0131m\u0131nda<\/strong> ve <strong>resmi i\u015flemlerde<\/strong> size tam destek sa\u011fl\u0131yoruz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9621\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9621\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Kurulu\u015f ve s\u00fcrekli destek i\u00e7in hangi maliyetler ortaya \u00e7\u0131kar? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-1220 e-n-accordion-item-9621\" class=\"elementor-element elementor-element-cd0a3b4 e-flex e-con-boxed e-con e-child\" data-id=\"cd0a3b4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-1220 e-n-accordion-item-9621\" class=\"elementor-element elementor-element-9d27154 e-flex e-con-boxed e-con e-child\" data-id=\"9d27154\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39bb60d elementor-widget elementor-widget-heading\" data-id=\"39bb60d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Maliyetler hizmet paketine g\u00f6re de\u011fi\u015fir. \u015eeffaf paketlerimiz \u015funlar\u0131 i\u00e7erir: <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-177c1b6 elementor-widget elementor-widget-text-editor\" data-id=\"177c1b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Maliyetler hizmet paketine g\u00f6re de\u011fi\u015fir.<br>ICI bireysel m\u00fc\u015fteri dan\u0131\u015fmanl\u0131\u011f\u0131 sunar ve buna g\u00f6re <b>hizmet paketleri<\/b> \u015firket b\u00fcy\u00fckl\u00fc\u011f\u00fcne g\u00f6re uyarlan\u0131r.<br><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-9622\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-9622\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Dan\u0131\u015fmanl\u0131\u011f\u0131n\u0131z\u0131 hangi dillerde sunuyorsunuz? <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-1220 e-n-accordion-item-9622\" class=\"elementor-element elementor-element-8d0f814 e-flex e-con-boxed e-con e-child\" data-id=\"8d0f814\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div role=\"region region\" aria-labelledby=\"e-n-accordion-item-1220 e-n-accordion-item-9622\" class=\"elementor-element elementor-element-dd98788 e-con-full e-flex e-con e-child\" data-id=\"dd98788\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8b1bf1b elementor-widget elementor-widget-text-editor\" data-id=\"8b1bf1b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Almanca, \u0130ngilizce ve Bulgarca<\/strong> dillerinde dan\u0131\u015fmanl\u0131k sa\u011fl\u0131yoruz.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Banka hesab\\u0131 a\\u00e7\\u0131l\\u0131\\u015f\\u0131 veya oturma izni konusunda destek sa\\u011fl\\u0131yor musunuz?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Evet, hesap a\\u00e7\\u0131l\\u0131\\u015f\\u0131nda, UID numaras\\u0131 ba\\u015fvurusunda, oturma kart\\u0131 al\\u0131m\\u0131nda ve resmi i\\u015flemlerde size tam destek sa\\u011fl\\u0131yoruz.\"}},{\"@type\":\"Question\",\"name\":\"Kurulu\\u015f ve s\\u00fcrekli destek i\\u00e7in hangi maliyetler ortaya \\u00e7\\u0131kar?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Maliyetler hizmet paketine g\\u00f6re de\\u011fi\\u015fir. \\u015eeffaf paketlerimiz \\u015funlar\\u0131 i\\u00e7erir: \\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\n\\t\\t\\t\\t\\t\\t\\t\\t\\tMaliyetler hizmet paketine g\\u00f6re de\\u011fi\\u015fir.ICI bireysel m\\u00fc\\u015fteri dan\\u0131\\u015fmanl\\u0131\\u011f\\u0131 sunar ve buna g\\u00f6re hizmet paketleri \\u015firket b\\u00fcy\\u00fckl\\u00fc\\u011f\\u00fcne g\\u00f6re uyarlan\\u0131r.\"}},{\"@type\":\"Question\",\"name\":\"Dan\\u0131\\u015fmanl\\u0131\\u011f\\u0131n\\u0131z\\u0131 hangi dillerde sunuyorsunuz?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Almanca, \\u0130ngilizce ve Bulgarca dillerinde dan\\u0131\\u015fmanl\\u0131k sa\\u011fl\\u0131yoruz.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e483254 e-flex e-con-boxed e-con e-parent\" data-id=\"e483254\" data-element_type=\"container\" data-e-type=\"container\" id=\"contact\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-25663e7 elementor-widget elementor-widget-spacer\" data-id=\"25663e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-085541e elementor-widget elementor-widget-heading\" data-id=\"085541e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vergi y\u00fck\u00fcn\u00fcz\u00fc <br>azaltmaya haz\u0131r m\u0131s\u0131n\u0131z?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36ba12e elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"36ba12e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa5eb76 elementor-widget elementor-widget-spacer\" data-id=\"aa5eb76\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-87c73cd e-con-full e-flex e-con e-child\" data-id=\"87c73cd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fd36d90 e-con-full e-flex e-con e-child\" data-id=\"fd36d90\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c9626ba elementor-widget elementor-widget-shortcode\" data-id=\"c9626ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><form id=\"forminator-module-3457\" class=\"forminator-custom-form forminator-custom-form-3457\" method=\"post\" data-forminator-render=\"0\" data-uid=\"6a04d57c45854\"><div role=\"alert\" aria-live=\"polite\" class=\"forminator-response-message forminator-error\" aria-hidden=\"true\"><\/div><\/form><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81e694c e-con-full e-flex e-con e-child\" data-id=\"81e694c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a5f9fbb elementor-widget elementor-widget-heading\" data-id=\"a5f9fbb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0130leti\u015fim ki\u015finiz<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6d019a elementor-widget elementor-widget-text-editor\" data-id=\"c6d019a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Birsen Karadayi<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d457a6e elementor-widget elementor-widget-text-editor\" data-id=\"d457a6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span class=\"elementor-icon-list-text\">Mobil\/Whatsapp +359 882 344 600<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5745ac elementor-widget elementor-widget-image\" data-id=\"f5745ac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"973\" height=\"1010\" src=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/07\/birsen.jpg\" class=\"attachment-large size-large wp-image-3451\" alt=\"\" srcset=\"https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/07\/birsen.jpg 973w, https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/07\/birsen-289x300.jpg 289w, https:\/\/investconsultint.com\/wp-content\/uploads\/2025\/07\/birsen-768x797.jpg 768w\" sizes=\"(max-width: 973px) 100vw, 973px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Vergi cennetine ho\u015f geldiniz Vergi cenneti Schengen&#8217;in. INVEST CONSULT INTERNATIONAL Bulgaristan&#8217;da \u015firket kurulu\u015fu ve i\u015fletme y\u00f6netiminde g\u00fcvenilir orta\u011f\u0131n\u0131z \u0130leti\u015fime ge\u00e7in Her ad\u0131mda yan\u0131n\u0131zda Kurulu\u015ftan pazar liderli\u011fine kadar ICI, m\u00fc\u015fterilerini ba\u015far\u0131ya giden yolda destekler &#8230; ve hatta bunun \u00e7ok \u00f6tesinde \u015eirket kurulu\u015fu Sorunsuz ve son derece kolay! Bulgaristan&#8217;da \u015firketinizi kurarken ICI ile ya\u015fayaca\u011f\u0131n\u0131z deneyim b\u00f6yle olacak. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"rank_math_title":"","rank_math_description":"","rank_math_focus_keyword":"","footnotes":""},"class_list":["post-3437","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/pages\/3437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/comments?post=3437"}],"version-history":[{"count":28,"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/pages\/3437\/revisions"}],"predecessor-version":[{"id":3485,"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/pages\/3437\/revisions\/3485"}],"wp:attachment":[{"href":"https:\/\/investconsultint.com\/tr\/wp-json\/wp\/v2\/media?parent=3437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}